{"id":701,"date":"2022-01-11T17:31:13","date_gmt":"2022-01-11T10:31:13","guid":{"rendered":"https:\/\/berliansakaperkasa.com\/?page_id=701"},"modified":"2023-10-18T23:18:11","modified_gmt":"2023-10-18T16:18:11","slug":"gasket","status":"publish","type":"page","link":"https:\/\/berliansakaperkasa.com\/en\/produk\/gasket\/","title":{"rendered":"Gasket"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"701\" class=\"elementor elementor-701\">\n\t\t\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-f588698 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f588698\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<section class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75f4c8b\" data-id=\"75f4c8b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23834d4 elementor-widget elementor-widget-heading\" data-id=\"23834d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gasket<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb922d elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3eb922d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0df6a42 elementor-widget elementor-widget-text-editor\" data-id=\"0df6a42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A gasket is a material used to fill the gap between two mating surfaces, such as in machinery or industrial equipment, to prevent leakage or loss of pressure. Gaskets can be made from various types of materials, such as heat-resistant paper, rubber, metal, or other synthetic materials.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d14317c elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"d14317c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<section class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d85d100\" data-id=\"d85d100\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a102f95 elementor-widget elementor-widget-heading\" data-id=\"a102f95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Detail Gasket<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-183ecac elementor-list-item-link-inline elementor-align-start elementor-tablet-align-start elementor-mobile-align-start elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"183ecac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Size : Standard \/ Customize<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Material : NBR \/ VITON \/ EPDM \/ Graphite \/ Paper etc<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bbbd25e\" data-id=\"bbbd25e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f54b7a elementor-widget elementor-widget-image-carousel\" data-id=\"3f54b7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;slides_to_scroll_tablet&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;no&quot;,&quot;autoplay_speed&quot;:2500,&quot;speed&quot;:250,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Karosel Gambar\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/IMG-Gasket-1.jpg\" alt=\"IMG Gasket 1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/IMG-Gasket-2.jpg\" alt=\"IMG Gasket 2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/IMG-Gasket-3.jpg\" alt=\"IMG Gasket 3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/IMG-Gasket-4.jpg\" alt=\"IMG Gasket 4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/IMG-Gasket-5.jpg\" alt=\"IMG Gasket 5\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/IMG-Gasket-6.jpg\" alt=\"IMG Gasket 6\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/IMG-Gasket-7.jpg\" alt=\"IMG Gasket 7\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/IMG-Gasket-8.jpg\" alt=\"IMG Gasket 8\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-152f329 elementor-widget elementor-widget-spacer\" data-id=\"152f329\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a12ce15 elementor-widget elementor-widget-heading\" data-id=\"a12ce15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vesconite Standard<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-485be84 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"485be84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abda823 elementor-widget elementor-widget-text-editor\" data-id=\"abda823\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>For the past six decades, Vesconite has been internationally recognized as a versatile and high-quality replacement for traditional bearing and bushing materials. Offering a unique combination of high load-bearing strength, low friction, and low wear, Vesconite does not require manual lubrication, even in harsh and dirty working environments.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-66fca44 elementor-section-full_width elementor-section-content-top elementor-section-height-default elementor-section-height-default\" data-id=\"66fca44\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<section class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-65f9915\" data-id=\"65f9915\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8faa35 elementor-widget elementor-widget-text-editor\" data-id=\"d8faa35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vesconite has been tested and proven in thousands of applications across various industries, ranging from general industry to marine, agriculture, and many others. Vesconite has impressive dimensional stability, and, unlike many synthetic alternatives, Vesconite retains its strength in wet conditions. It exhibits insignificant deformation under high loads. Vesconite is available in a variety of rod sizes, bushings, plates, and machined custom parts.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3cb9a37\" data-id=\"3cb9a37\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b236e0e elementor-widget elementor-widget-image\" data-id=\"b236e0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/10\/Bersa-Vesconite-Standard.jpg\" class=\"attachment-full size-full wp-image-1805\" alt=\"Bersa - Vesconite Standard\" srcset=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/10\/Bersa-Vesconite-Standard.jpg 600w, https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/10\/Bersa-Vesconite-Standard-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d21df4 elementor-widget elementor-widget-spacer\" data-id=\"9d21df4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b91e4ff elementor-widget elementor-widget-heading\" data-id=\"b91e4ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vesconite Hilube<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96407f9 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"96407f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c885e70 elementor-widget elementor-widget-text-editor\" data-id=\"c885e70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vesconite Hilube is our premier bushing material designed for the toughest operating environments. Vesconite Hilube is specifically recommended for wet and underwater applications. This includes the pump and marine industries, where routine maintenance is practically impossible or not cost-effective. With superior wear life, especially in poorly lubricated and dirty conditions, Vesconite Hilube has been proven to offer up to ten times the life of bronze bushings.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c3aed09 elementor-section-full_width elementor-section-content-top elementor-section-height-default elementor-section-height-default\" data-id=\"c3aed09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<section class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-49a4b32\" data-id=\"49a4b32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-927b1e3 elementor-widget elementor-widget-text-editor\" data-id=\"927b1e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vesconite Hilube incorporates internal lubricants that result in an extremely low coefficient of friction. Coupled with excellent dimensional stability, low wear rates, and high load-bearing capacity, Vesconite Hilube has a PV (pressure x velocity) rating four times that of nylon bushings. Vesconite is available in a variety of rod sizes, bushings, plates, and machined custom parts.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ca623e2\" data-id=\"ca623e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29b806e elementor-widget elementor-widget-image\" data-id=\"29b806e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/10\/Bersa-Vesconite-Hilube.jpg\" class=\"attachment-full size-full wp-image-1806\" alt=\"Bersa - Vesconite Hilube\" srcset=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/10\/Bersa-Vesconite-Hilube.jpg 600w, https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/10\/Bersa-Vesconite-Hilube-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b799d90 elementor-widget elementor-widget-spacer\" data-id=\"b799d90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1f6106 elementor-widget elementor-widget-heading\" data-id=\"b1f6106\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vesconite Superlube<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea1b556 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ea1b556\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a486306 elementor-widget elementor-widget-text-editor\" data-id=\"a486306\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vesconite Superlube is a bushing material with the lowest coefficient of friction compared to other available bushing materials. It has a lower coefficient of friction than pure PTFE (polytetrafluoroethylene).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ff8ce8f elementor-section-full_width elementor-section-content-top elementor-section-height-default elementor-section-height-default\" data-id=\"ff8ce8f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<section class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c539103\" data-id=\"c539103\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73d67a9 elementor-widget elementor-widget-text-editor\" data-id=\"73d67a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vesconite Superlube is extraordinary because in addition to having low friction, it also has excellent load-bearing capabilities with extremely low wear rates. We provide stock rods, hollow bars, plates, and with our 80 CNC machines, we can machine parts according to the drawings you provide.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8ebf0c7\" data-id=\"8ebf0c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e845562 elementor-widget elementor-widget-image\" data-id=\"e845562\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/10\/Bersa-Vesconite-Superlube.jpg\" class=\"attachment-full size-full wp-image-1807\" alt=\"Bersa - Vesconite Superlube\" srcset=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/10\/Bersa-Vesconite-Superlube.jpg 600w, https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/10\/Bersa-Vesconite-Superlube-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-11c1913 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11c1913\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<section class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-21976fc\" data-id=\"21976fc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b16fa90 elementor-widget elementor-widget-heading\" data-id=\"b16fa90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contact Us Now and Get the Best Offer!<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f70697 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2f70697\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8599343 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"8599343\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<section class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0ffa754\" data-id=\"0ffa754\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f5adf2 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1f5adf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:02476606627\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">(024) 7660-6627<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1acc921\" data-id=\"1acc921\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19b20a3 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"19b20a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/api.whatsapp.com\/send?phone=6282110782686&#038;text=Halo%20Sales%20Support%20*Berliansakaperkasa.com*,%20saya%20ingin%20mendapatkan%20penawaran%20terbaik%20untuk%20*Produk%20Gaset*\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">0822-2661-7956<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2808885\" data-id=\"2808885\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d14ef1c elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"d14ef1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:sales@berliansakaperkasa.com\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">sales@berliansakaperkasa.com<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Gasket Gasket adalah bahan yang digunakan untuk mengisi celah antara dua permukaan yang saling berhubungan, seperti pada mesin atau peralatan industri, guna mencegah kebocoran atau kehilangan tekanan. Gasket dapat terbuat dari berbagai jenis material, seperti kertas tahan panas, karet, logam, atau bahan sintetis lainnya. Detail Gasket Size : Standard \/ Customize Material : NBR \/ [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1366,"parent":1311,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"ocean_front_end_style_editor":"no","ocean_post_layout":"full-width","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"enable","ocean_disable_heading":"enable","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"on","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"on","ocean_display_footer_bottom":"on","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-701","page","type-page","status-publish","has-post-thumbnail","hentry","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gasket - CV. Berlian Saka Perkasa Engineering<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/berliansakaperkasa.com\/en\/produk\/gasket\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gasket\" \/>\n<meta property=\"og:description\" content=\"Gasket Gasket adalah bahan yang digunakan untuk mengisi celah antara dua permukaan yang saling berhubungan, seperti pada mesin atau peralatan industri,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/berliansakaperkasa.com\/en\/produk\/gasket\/\" \/>\n<meta property=\"og:site_name\" content=\"CV. Berlian Saka Perkasa Engineering\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-18T16:18:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/Cover-Gasket2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/Cover-Gasket2.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/berliansakaperkasa.com\\\/produk\\\/gasket\\\/\",\"url\":\"https:\\\/\\\/berliansakaperkasa.com\\\/produk\\\/gasket\\\/\",\"name\":\"Gasket - CV. Berlian Saka Perkasa Engineering\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/berliansakaperkasa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/berliansakaperkasa.com\\\/produk\\\/gasket\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/berliansakaperkasa.com\\\/produk\\\/gasket\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/berliansakaperkasa.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Logo-Web-CV-Berlian-Saka-Perkasa-2023.jpg\",\"datePublished\":\"2022-01-11T10:31:13+00:00\",\"dateModified\":\"2023-10-18T16:18:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/berliansakaperkasa.com\\\/produk\\\/gasket\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/berliansakaperkasa.com\\\/produk\\\/gasket\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/berliansakaperkasa.com\\\/produk\\\/gasket\\\/#primaryimage\",\"url\":\"https:\\\/\\\/berliansakaperkasa.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Logo-Web-CV-Berlian-Saka-Perkasa-2023.jpg\",\"contentUrl\":\"https:\\\/\\\/berliansakaperkasa.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Logo-Web-CV-Berlian-Saka-Perkasa-2023.jpg\",\"width\":709,\"height\":709,\"caption\":\"Logo Web CV Berlian Saka Perkasa 2023\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/berliansakaperkasa.com\\\/produk\\\/gasket\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/berliansakaperkasa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produk\",\"item\":\"https:\\\/\\\/berliansakaperkasa.com\\\/produk\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gasket\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/berliansakaperkasa.com\\\/#website\",\"url\":\"https:\\\/\\\/berliansakaperkasa.com\\\/\",\"name\":\"CV. Berlian Saka Perkasa Engineering\",\"description\":\"Sparepart Industri dengan Harga Terjangkau dan Menawarkan Solusi yang Terbaik\",\"publisher\":{\"@id\":\"https:\\\/\\\/berliansakaperkasa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/berliansakaperkasa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/berliansakaperkasa.com\\\/#organization\",\"name\":\"CV. Berlian Saka Perkasa Engineering\",\"url\":\"https:\\\/\\\/berliansakaperkasa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/berliansakaperkasa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/berliansakaperkasa.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logo-Situs-CV-Berlian-Saka-Perkasa-Engineering-082226617956.png\",\"contentUrl\":\"https:\\\/\\\/berliansakaperkasa.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logo-Situs-CV-Berlian-Saka-Perkasa-Engineering-082226617956.png\",\"width\":502,\"height\":88,\"caption\":\"CV. Berlian Saka Perkasa Engineering\"},\"image\":{\"@id\":\"https:\\\/\\\/berliansakaperkasa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gasket - CV. Berlian Saka Perkasa Engineering","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/berliansakaperkasa.com\/en\/produk\/gasket\/","og_locale":"en_US","og_type":"article","og_title":"Gasket","og_description":"Gasket Gasket adalah bahan yang digunakan untuk mengisi celah antara dua permukaan yang saling berhubungan, seperti pada mesin atau peralatan industri,","og_url":"https:\/\/berliansakaperkasa.com\/en\/produk\/gasket\/","og_site_name":"CV. Berlian Saka Perkasa Engineering","article_modified_time":"2023-10-18T16:18:11+00:00","og_image":[{"width":600,"height":480,"url":"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/Cover-Gasket2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/Cover-Gasket2.jpg","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/berliansakaperkasa.com\/produk\/gasket\/","url":"https:\/\/berliansakaperkasa.com\/produk\/gasket\/","name":"Gasket - CV. Berlian Saka Perkasa Engineering","isPartOf":{"@id":"https:\/\/berliansakaperkasa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/berliansakaperkasa.com\/produk\/gasket\/#primaryimage"},"image":{"@id":"https:\/\/berliansakaperkasa.com\/produk\/gasket\/#primaryimage"},"thumbnailUrl":"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/Logo-Web-CV-Berlian-Saka-Perkasa-2023.jpg","datePublished":"2022-01-11T10:31:13+00:00","dateModified":"2023-10-18T16:18:11+00:00","breadcrumb":{"@id":"https:\/\/berliansakaperkasa.com\/produk\/gasket\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/berliansakaperkasa.com\/produk\/gasket\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/berliansakaperkasa.com\/produk\/gasket\/#primaryimage","url":"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/Logo-Web-CV-Berlian-Saka-Perkasa-2023.jpg","contentUrl":"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2023\/02\/Logo-Web-CV-Berlian-Saka-Perkasa-2023.jpg","width":709,"height":709,"caption":"Logo Web CV Berlian Saka Perkasa 2023"},{"@type":"BreadcrumbList","@id":"https:\/\/berliansakaperkasa.com\/produk\/gasket\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/berliansakaperkasa.com\/"},{"@type":"ListItem","position":2,"name":"Produk","item":"https:\/\/berliansakaperkasa.com\/produk\/"},{"@type":"ListItem","position":3,"name":"Gasket"}]},{"@type":"WebSite","@id":"https:\/\/berliansakaperkasa.com\/#website","url":"https:\/\/berliansakaperkasa.com\/","name":"CV. Berlian Saka Perkasa Engineering","description":"Sparepart Industri dengan Harga Terjangkau dan Menawarkan Solusi yang Terbaik","publisher":{"@id":"https:\/\/berliansakaperkasa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/berliansakaperkasa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/berliansakaperkasa.com\/#organization","name":"CV. Berlian Saka Perkasa Engineering","url":"https:\/\/berliansakaperkasa.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/berliansakaperkasa.com\/#\/schema\/logo\/image\/","url":"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2021\/04\/Logo-Situs-CV-Berlian-Saka-Perkasa-Engineering-082226617956.png","contentUrl":"https:\/\/berliansakaperkasa.com\/wp-content\/uploads\/2021\/04\/Logo-Situs-CV-Berlian-Saka-Perkasa-Engineering-082226617956.png","width":502,"height":88,"caption":"CV. Berlian Saka Perkasa Engineering"},"image":{"@id":"https:\/\/berliansakaperkasa.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/berliansakaperkasa.com\/en\/wp-json\/wp\/v2\/pages\/701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berliansakaperkasa.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/berliansakaperkasa.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/berliansakaperkasa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/berliansakaperkasa.com\/en\/wp-json\/wp\/v2\/comments?post=701"}],"version-history":[{"count":61,"href":"https:\/\/berliansakaperkasa.com\/en\/wp-json\/wp\/v2\/pages\/701\/revisions"}],"predecessor-version":[{"id":1821,"href":"https:\/\/berliansakaperkasa.com\/en\/wp-json\/wp\/v2\/pages\/701\/revisions\/1821"}],"up":[{"embeddable":true,"href":"https:\/\/berliansakaperkasa.com\/en\/wp-json\/wp\/v2\/pages\/1311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berliansakaperkasa.com\/en\/wp-json\/wp\/v2\/media\/1366"}],"wp:attachment":[{"href":"https:\/\/berliansakaperkasa.com\/en\/wp-json\/wp\/v2\/media?parent=701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}